{"id":7868,"date":"2020-03-23T21:42:45","date_gmt":"2020-03-23T21:42:45","guid":{"rendered":"https:\/\/www.performia.com\/?p=7868"},"modified":"2022-09-29T16:07:08","modified_gmt":"2022-09-29T16:07:08","slug":"los-principales-criterios-en-la-contratacion","status":"publish","type":"post","link":"https:\/\/www.performia.com\/es_co\/los-principales-criterios-en-la-contratacion\/","title":{"rendered":"Los principales criterios en la contrataci\u00f3n"},"content":{"rendered":"<p><strong>Al reclutar gente nueva hay un factor que usted tiene que establecer firmemente antes de decidir con seguridad traer a una nueva persona a bordo.<\/strong><\/p>\n<h4>\u00bfR\u00e9cord de producci\u00f3n?<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6881 alignright\" src=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/recruitment-1.png\" alt=\"\" width=\"536\" height=\"453\" srcset=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/recruitment-1.png 903w, https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/recruitment-1-355x300.png 355w, https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/recruitment-1-768x650.png 768w\" sizes=\"auto, (max-width: 536px) 100vw, 536px\" \/><\/p>\n<p>El primer y con mucho, el factor m\u00e1s importante en la contrataci\u00f3n es establecer y entender el RECORD DE PRODUCCI\u00d3N de un candidato.<\/p>\n<p>Un &#8220;producto&#8221; se puede definir como el resultado final valioso de un esfuerzo dirigido para completar un art\u00edculo o actividad.\u00a0Y el hecho de que realmente est\u00e1 completado, es valioso, funciona y no necesita m\u00e1s atenciones son todos los atributos de un producto.\u00a0Usted compra una m\u00e1quina de perforaci\u00f3n, y cuando llega a casa para usarlo se da cuenta de que el taladro no es estable, sino que vibra mucho y hace casi imposible la perforaci\u00f3n.\u00a0Esa m\u00e1quina simplemente no era un buen producto.\u00a0Necesita m\u00e1s atenci\u00f3n antes de que pueda convertirse en uno.\u00a0Entregar cosas que est\u00e1n totalmente funcionando y completas es la responsabilidad clave de los l\u00edderes.\u00a0Lo mismo es cierto para todo el personal que tiene.\u00a0Se supone que todos y cada uno de los miembros de su organizaci\u00f3n ofrecen valor a trav\u00e9s de la entrega de &#8220;productos&#8221;.<\/p>\n<h4>Definici\u00f3n de un producto<\/h4>\n<p>Un producto, para ser llamado &#8220;producto&#8221;, no tiene que ser un objeto f\u00edsico;\u00a0tambi\u00e9n podr\u00eda ser la completaci\u00f3n de un servicio.\u00a0En la sociedad actual, tenemos, de hecho, una tendencia a desarrollar y entregar cada vez m\u00e1s productos que son servicios asistidos personalmente o por una m\u00e1quina.\u00a0Estos podr\u00edan ser ventanas limpias, dientes reparados, una asesor\u00eda que resulta en un plan de negocios adecuado y viable, acceso a Internet, etc.\u00a0 Todos estos son productos en el sentido de la palabra que estamos usando aqu\u00ed.\u00a0Y tambi\u00e9n deben ser necesarios y requeridos.\u00a0La entrega de los productos de una empresa es la \u00fanica raz\u00f3n de su existencia.<\/p>\n<h4>Comprender los productos de su empresa es vital<\/h4>\n<p>Esto puede sonar demasiado simple e innecesario para mencionar, pero, si este concepto de producto no se entiende completamente y se aplica tanto a la gerencia como al personal, no ser\u00e1 tan exitoso como potencialmente podr\u00eda ser en la contrataci\u00f3n.\u00a0Es vital no s\u00f3lo entender qu\u00e9 diferentes productos tiene su organizaci\u00f3n, sino tambi\u00e9n qu\u00e9 productos se supone que cada uno de sus miembros del personal debe entregar, si desea obtener todos los beneficios de este sistema de contrataci\u00f3n.<\/p>\n<p>Para entregar una gran cantidad de productos con alta calidad y suficiente volumen requiere personal que est\u00e9 dispuesto, capacitado e interesado lo suficiente para hacerlo realidad.\u00a0Y es por eso que lo ideal es tener una verificaci\u00f3n del registro de producci\u00f3n de cada persona que alguna vez tiene la intenci\u00f3n de contratar, o al menos investigar el \u00e1rea cuidadosamente para los nuevos candidatos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6773\" src=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria.jpg\" alt=\"\" width=\"803\" height=\"467\" srcset=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria.jpg 803w, https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria-516x300.jpg 516w, https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria-768x447.jpg 768w\" sizes=\"auto, (max-width: 803px) 100vw, 803px\" \/><\/p>\n<h4>Permanecer en la empresa por un per\u00edodo largo de tiempo<\/h4>\n<p>El segundo prerrequisito que necesita considerar es que est\u00e1 lidiando con una persona que es capaz y dispuesta de PERMANECER EN LA EMPRESA por un per\u00edodo de tiempo razonable.\u00a0 Desafortunadamente, existen muchas personas que cambian de puestos y empresas tan pronto se les ofrece m\u00e1s dinero en otro lugar, o que se van cuando sucede alg\u00fan problema inesperado, o que simplemente carecen de persistencia.<\/p>\n<p>Para establecer cu\u00e1les son las posibilidades de que un candidato est\u00e9 dispuesto y capaz de permanecer por un periodo largo, tendr\u00e1 que mirar un par de factores.\u00a0 Uno es el antecedente del candidato con respecto a la duraci\u00f3n del empleo con empleadores anteriores, y el otro es la personalidad.\u00a0 Ciertas personalidades son muy definidas acerca de querer aprender un trabajo a fondo para luego experimentar la satisfacci\u00f3n de tener total certeza en c\u00f3mo hacer el trabajo, y por lo tanto tienen poco o ning\u00fan impulso de cambiar s\u00f3lo para entrar en algo nuevo.\u00a0 Otros est\u00e1n principalmente interesados en nuevos niveles del mismo trabajo o un trabajo muy similar, mientras que otras personas se aburren cuando sienten que\u201d lo saben todo\u201d y por lo tanto prefieren cambiar y participar en un desaf\u00edo completamente nuevo o diferente.\u00a0 Esta es un \u00e1rea donde las pruebas de personalidad de Performia realmente pueden proporcionar informaci\u00f3n vital sobre lo que puede hacer para tratar con el personal individualmente, con el fin de aumentar las posibilidades de mantenerlos por m\u00e1s tiempo.<\/p>\n<h4>Funcionamiento dentro de un grupo<\/h4>\n<p>La tercera \u00e1rea que debe considerar antes de tomar su decisi\u00f3n final de contrataci\u00f3n es evaluar la capacidad de la persona para funcionar dentro de un grupo y, por lo tanto, la capacidad de crear relaciones decentes y duraderas con otras personas.\u00a0 A veces, (raramente, sin embargo) encontrar\u00e1 una persona que es realmente productiva mientras trabaja sola, pero tiene un problema de cooperaci\u00f3n con otros hasta tal punto que arruina la productividad general del grupo.\u00a0 Si es as\u00ed, se convierte en un reclutamiento negativo, o, en otras palabras, una persona que no debe contratar.\u00a0 Nosotros, en Performia, consideramos vital entender este \u00faltimo factor antes de tomar la decisi\u00f3n de contrataci\u00f3n.<\/p>\n<h4>Conocimiento sobre la personalidad de una persona<\/h4>\n<p>Es un hecho que cuanto m\u00e1s conocimiento tenga sobre la personalidad de una persona (tanto positiva como negativa), m\u00e1s f\u00e1cil ser\u00e1 para usted asumir la responsabilidad de utilizar a esa persona correctamente, y as\u00ed asegurarse de que la empresa aproveche sus habilidades, mientras que evita poner a esa persona en situaciones donde sus debilidades ser\u00e1n \u201cvisibles, evidentes\u201d.\u00a0 Por lo tanto, idealmente, debe tener suficiente informaci\u00f3n para que usted como administrador, pueda predecir posibles escenarios negativos donde la producci\u00f3n podr\u00eda perjudicarse y, en su lugar, crear posibles soluciones tanto para el individuo en cuesti\u00f3n como para el grupo.\u00a0 De hecho, tales escenarios deben y pueden reducirse y eliminarse idealmente.\u00a0 Cuanto m\u00e1s sepa acerca de las \u00e1reas fuertes y d\u00e9biles de una persona, mejor podr\u00e1 asumir la responsabilidad y asegurarse de que las cosas vayan bien para la empresa, as\u00ed como para usted y el nuevo empleado.<\/p>\n<h4>La peor combinaci\u00f3n<\/h4>\n<p>La peor combinaci\u00f3n de estos tres factores es, naturalmente, una persona que no se desempe\u00f1a bien ni es productiva, y que tiene grandes problemas para cooperar con los dem\u00e1s, pero que con seguridad se quedar\u00e1 y nunca se ir\u00e1. Desafortunadamente, esta es la realidad con la que usted como gerente a veces se encontrar\u00e1.<\/p>\n<h4><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-6809 alignleft\" src=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria_2.jpg\" alt=\"\" width=\"495\" height=\"448\" srcset=\"https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria_2.jpg 572w, https:\/\/www.performia.com\/wp-content\/uploads\/2020\/03\/main_criteria_2-331x300.jpg 331w\" sizes=\"auto, (max-width: 495px) 100vw, 495px\" \/>Atrayendo a las personas adecuadas<\/h4>\n<p>Performia se especializa en educar a los empresarios de todo el mundo, no solo en c\u00f3mo detectar y contratar a esas personas de alta calidad, productivas, leales y cooperativas que pueden ayudar a que su negocio crezca, sino tambi\u00e9n en lo que necesita hacer para convencer realmente a ese tipo de personas para aplicar a su empresa.<\/p>\n<p>Ciertamente, hay m\u00e1s criterios que pueden y deben considerarse, pero normalmente son subsecciones de las tres \u00e1reas anteriores. Por ejemplo, el nivel de habilidad t\u00e9cnica. En algunos trabajos, ese es el punto m\u00e1s cr\u00edtico a tener en cuenta, para garantizar la posibilidad de cualquier productividad. Un ejemplo de esto podr\u00eda ser la programaci\u00f3n inform\u00e1tica avanzada. Para tener la m\u00e1s m\u00ednima posibilidad de ser productivo en ese rol, normalmente necesita de experiencia bastante exitosa. \u00bfCu\u00e1nto tiempo le toma a una persona con poco o ning\u00fan conocimiento sobre programaci\u00f3n poder realmente funcionar y, por lo tanto, contribuir individualmente en un nivel realmente alto en una posici\u00f3n de programaci\u00f3n avanzada? La mayor\u00eda de nosotros sabemos que podr\u00eda llevar a\u00f1os. Y sin esa experiencia especializada, realmente no importa cu\u00e1n social, servicial y racional sea la persona en general.<\/p>\n<p>A veces vemos empresas que tienen a sus programadores ubicados en un \u00e1rea de alta seguridad de las instalaciones, y a menudo no vemos a mucha de esa gente durante el horario de trabajo com\u00fan. Aun as\u00ed, podr\u00edan ser una de las claves del \u00e9xito de toda la operaci\u00f3n. Sus personalidades a menudo no son &#8220;ideales&#8221; y es posible que no desee que hablen directamente con sus clientes. Sin embargo, para encontrar lo que necesita ser reparado y corregido dentro de su sistema, ellos pueden ser de importancia vital.<\/p>\n<p>No obstante, nuestra necesidad de encontrar resultados valiosos reales producidos en el pasado nunca se reduce a alguien que tiene alg\u00fan &#8220;conocimiento especializado&#8221;, porque si ese conocimiento realmente no ha resultado en valor y producci\u00f3n hasta el momento, es muy poco probable que suceda en el futuro. Usted, al menos debe saber que est\u00e1 asumiendo un riesgo enorme cuando contrata en base a la esperanza \u2013 lo cual simplemente no se recomienda- en lugar de hacerlo basado en hechos observables y resultados comprobados.<\/p>\n<p><em>M\u00e5rten Runow<\/em><br \/>\n<em>Fundador de Performia Internacional<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al reclutar gente nueva hay un factor que usted tiene que establecer firmemente antes de decidir con seguridad traer a una nueva persona a bordo. \u00bfR\u00e9cord de producci\u00f3n? El primer y con mucho, el factor m\u00e1s importante en la contrataci\u00f3n es establecer y entender el RECORD DE PRODUCCI\u00d3N de un candidato. Un &#8220;producto&#8221; se puede&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6596,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[10083],"tags":[10157],"class_list":["post-7868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-previous-es_co","tag-issue-2-es_co"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/posts\/7868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/comments?post=7868"}],"version-history":[{"count":3,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/posts\/7868\/revisions"}],"predecessor-version":[{"id":7922,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/posts\/7868\/revisions\/7922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/media\/6596"}],"wp:attachment":[{"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/media?parent=7868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/categories?post=7868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.performia.com\/es_co\/wp-json\/wp\/v2\/tags?post=7868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}